{"id":1405,"date":"2024-11-21T14:29:02","date_gmt":"2024-11-21T14:29:02","guid":{"rendered":"https:\/\/leaebeling.de\/?p=1405"},"modified":"2025-02-20T09:54:48","modified_gmt":"2025-02-20T09:54:48","slug":"weltschmerz","status":"publish","type":"post","link":"https:\/\/leaebeling.de\/en\/weltschmerz\/","title":{"rendered":"Weltschmerz"},"content":{"rendered":"<div class=\"wp-block-group alignfull has-base-2-background-color has-background is-vertical is-content-justification-stretch is-nowrap is-layout-flex wp-container-core-group-is-layout-de88b632 wp-block-group-is-layout-flex\" style=\"border-style:none;border-width:0px;margin-top:0;margin-bottom:0;padding-top:var(--wp--preset--spacing--30);padding-right:var(--wp--preset--spacing--30);padding-bottom:var(--wp--preset--spacing--30);padding-left:var(--wp--preset--spacing--30)\">\n<div class=\"wp-block-group is-vertical is-layout-flex wp-container-core-group-is-layout-893ba88d wp-block-group-is-layout-flex\" style=\"margin-top:0;margin-bottom:0\"><div class=\"taxonomy-category wp-block-post-terms\"><a href=\"https:\/\/leaebeling.de\/en\/category\/illustration\/\" rel=\"tag\">Illustration<\/a><span class=\"wp-block-post-terms__separator\">, <\/span><a href=\"https:\/\/leaebeling.de\/en\/category\/wissenschaftskommunikation\/\" rel=\"tag\">Science Communication<\/a><\/div>\n\n<h2 class=\"wp-block-post-title\">Weltschmerz<\/h2>\n\n\n<p class=\"has-large-font-size wp-block-paragraph\">Political Emotions in the Neoliberal Age<\/p>\n<\/div>\n\n\n\n<div class=\"wp-block-columns alignwide is-layout-flex wp-container-core-columns-is-layout-3506bd9a wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-vertically-aligned-center is-layout-flow wp-container-core-column-is-layout-3a817d93 wp-block-column-is-layout-flow\" style=\"padding-right:var(--wp--preset--spacing--30);padding-left:var(--wp--preset--spacing--30);flex-basis:30%\">\n<p class=\"has-montserrat-font-family has-medium-font-size wp-block-paragraph\">Illustrations for a video one world-weariness. Research based on an ethnographic study.<\/p>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-vertically-aligned-top is-layout-flow wp-container-core-column-is-layout-4de666df wp-block-column-is-layout-flow\" style=\"padding-right:0;padding-left:0;flex-basis:70%\">\n<div class=\"wp-block-jetpack-slideshow aligncenter is-style-rounded\" data-effect=\"slide\"><div class=\"wp-block-jetpack-slideshow_container swiper-container\"><ul class=\"wp-block-jetpack-slideshow_swiper-wrapper swiper-wrapper\"><li class=\"wp-block-jetpack-slideshow_slide swiper-slide\"><figure><img loading=\"lazy\" decoding=\"async\" width=\"14234\" height=\"8012\" alt=\"\" class=\"wp-block-jetpack-slideshow_image wp-image-1407\" data-id=\"1407\" src=\"https:\/\/leaebeling.de\/wp-content\/uploads\/2024\/11\/Anger.png\" srcset=\"https:\/\/leaebeling.de\/wp-content\/uploads\/2024\/11\/Anger.png 14234w, https:\/\/leaebeling.de\/wp-content\/uploads\/2024\/11\/Anger-300x169.png 300w, https:\/\/leaebeling.de\/wp-content\/uploads\/2024\/11\/Anger-1024x576.png 1024w, https:\/\/leaebeling.de\/wp-content\/uploads\/2024\/11\/Anger-1280x720.png 1280w, https:\/\/leaebeling.de\/wp-content\/uploads\/2024\/11\/Anger-768x432.png 768w, https:\/\/leaebeling.de\/wp-content\/uploads\/2024\/11\/Anger-1536x865.png 1536w, https:\/\/leaebeling.de\/wp-content\/uploads\/2024\/11\/Anger-2048x1153.png 2048w, https:\/\/leaebeling.de\/wp-content\/uploads\/2024\/11\/Anger-500x281.png 500w, https:\/\/leaebeling.de\/wp-content\/uploads\/2024\/11\/Anger-800x450.png 800w, https:\/\/leaebeling.de\/wp-content\/uploads\/2024\/11\/Anger-1920x1081.png 1920w\" sizes=\"auto, (max-width: 14234px) 100vw, 14234px\" \/><\/figure><\/li><li class=\"wp-block-jetpack-slideshow_slide swiper-slide\"><figure><img loading=\"lazy\" decoding=\"async\" width=\"14234\" height=\"8012\" alt=\"\" class=\"wp-block-jetpack-slideshow_image wp-image-1409\" data-id=\"1409\" src=\"https:\/\/leaebeling.de\/wp-content\/uploads\/2024\/11\/Grief.png\" srcset=\"https:\/\/leaebeling.de\/wp-content\/uploads\/2024\/11\/Grief.png 14234w, https:\/\/leaebeling.de\/wp-content\/uploads\/2024\/11\/Grief-300x169.png 300w, https:\/\/leaebeling.de\/wp-content\/uploads\/2024\/11\/Grief-1024x576.png 1024w, https:\/\/leaebeling.de\/wp-content\/uploads\/2024\/11\/Grief-1280x720.png 1280w, https:\/\/leaebeling.de\/wp-content\/uploads\/2024\/11\/Grief-768x432.png 768w, https:\/\/leaebeling.de\/wp-content\/uploads\/2024\/11\/Grief-1536x865.png 1536w, https:\/\/leaebeling.de\/wp-content\/uploads\/2024\/11\/Grief-2048x1153.png 2048w, https:\/\/leaebeling.de\/wp-content\/uploads\/2024\/11\/Grief-500x281.png 500w, https:\/\/leaebeling.de\/wp-content\/uploads\/2024\/11\/Grief-800x450.png 800w, https:\/\/leaebeling.de\/wp-content\/uploads\/2024\/11\/Grief-1920x1081.png 1920w\" sizes=\"auto, (max-width: 14234px) 100vw, 14234px\" \/><\/figure><\/li><li class=\"wp-block-jetpack-slideshow_slide swiper-slide\"><figure><img loading=\"lazy\" decoding=\"async\" width=\"14234\" height=\"8012\" alt=\"\" class=\"wp-block-jetpack-slideshow_image wp-image-1410\" data-id=\"1410\" src=\"https:\/\/leaebeling.de\/wp-content\/uploads\/2024\/11\/Guilt.png\" srcset=\"https:\/\/leaebeling.de\/wp-content\/uploads\/2024\/11\/Guilt.png 14234w, https:\/\/leaebeling.de\/wp-content\/uploads\/2024\/11\/Guilt-300x169.png 300w, https:\/\/leaebeling.de\/wp-content\/uploads\/2024\/11\/Guilt-1024x576.png 1024w, https:\/\/leaebeling.de\/wp-content\/uploads\/2024\/11\/Guilt-1280x720.png 1280w, https:\/\/leaebeling.de\/wp-content\/uploads\/2024\/11\/Guilt-768x432.png 768w, https:\/\/leaebeling.de\/wp-content\/uploads\/2024\/11\/Guilt-1536x865.png 1536w, https:\/\/leaebeling.de\/wp-content\/uploads\/2024\/11\/Guilt-2048x1153.png 2048w, https:\/\/leaebeling.de\/wp-content\/uploads\/2024\/11\/Guilt-500x281.png 500w, https:\/\/leaebeling.de\/wp-content\/uploads\/2024\/11\/Guilt-800x450.png 800w, https:\/\/leaebeling.de\/wp-content\/uploads\/2024\/11\/Guilt-1920x1081.png 1920w\" sizes=\"auto, (max-width: 14234px) 100vw, 14234px\" \/><\/figure><\/li><li class=\"wp-block-jetpack-slideshow_slide swiper-slide\"><figure><img loading=\"lazy\" decoding=\"async\" width=\"14234\" height=\"8012\" alt=\"\" class=\"wp-block-jetpack-slideshow_image wp-image-1411\" data-id=\"1411\" src=\"https:\/\/leaebeling.de\/wp-content\/uploads\/2024\/11\/Helplessness.png\" srcset=\"https:\/\/leaebeling.de\/wp-content\/uploads\/2024\/11\/Helplessness.png 14234w, https:\/\/leaebeling.de\/wp-content\/uploads\/2024\/11\/Helplessness-300x169.png 300w, https:\/\/leaebeling.de\/wp-content\/uploads\/2024\/11\/Helplessness-1024x576.png 1024w, https:\/\/leaebeling.de\/wp-content\/uploads\/2024\/11\/Helplessness-1280x720.png 1280w, https:\/\/leaebeling.de\/wp-content\/uploads\/2024\/11\/Helplessness-768x432.png 768w, https:\/\/leaebeling.de\/wp-content\/uploads\/2024\/11\/Helplessness-1536x865.png 1536w, https:\/\/leaebeling.de\/wp-content\/uploads\/2024\/11\/Helplessness-2048x1153.png 2048w, https:\/\/leaebeling.de\/wp-content\/uploads\/2024\/11\/Helplessness-500x281.png 500w, https:\/\/leaebeling.de\/wp-content\/uploads\/2024\/11\/Helplessness-800x450.png 800w, https:\/\/leaebeling.de\/wp-content\/uploads\/2024\/11\/Helplessness-1920x1081.png 1920w\" sizes=\"auto, (max-width: 14234px) 100vw, 14234px\" \/><\/figure><\/li><li class=\"wp-block-jetpack-slideshow_slide swiper-slide\"><figure><img loading=\"lazy\" decoding=\"async\" width=\"14234\" height=\"8012\" alt=\"\" class=\"wp-block-jetpack-slideshow_image wp-image-1414\" data-id=\"1414\" src=\"https:\/\/leaebeling.de\/wp-content\/uploads\/2024\/11\/Shame.png\" srcset=\"https:\/\/leaebeling.de\/wp-content\/uploads\/2024\/11\/Shame.png 14234w, https:\/\/leaebeling.de\/wp-content\/uploads\/2024\/11\/Shame-300x169.png 300w, https:\/\/leaebeling.de\/wp-content\/uploads\/2024\/11\/Shame-1024x576.png 1024w, https:\/\/leaebeling.de\/wp-content\/uploads\/2024\/11\/Shame-1280x720.png 1280w, https:\/\/leaebeling.de\/wp-content\/uploads\/2024\/11\/Shame-768x432.png 768w, https:\/\/leaebeling.de\/wp-content\/uploads\/2024\/11\/Shame-1536x865.png 1536w, https:\/\/leaebeling.de\/wp-content\/uploads\/2024\/11\/Shame-2048x1153.png 2048w, https:\/\/leaebeling.de\/wp-content\/uploads\/2024\/11\/Shame-500x281.png 500w, https:\/\/leaebeling.de\/wp-content\/uploads\/2024\/11\/Shame-800x450.png 800w, https:\/\/leaebeling.de\/wp-content\/uploads\/2024\/11\/Shame-1920x1081.png 1920w\" sizes=\"auto, (max-width: 14234px) 100vw, 14234px\" \/><\/figure><\/li><li class=\"wp-block-jetpack-slideshow_slide swiper-slide\"><figure><img loading=\"lazy\" decoding=\"async\" width=\"14234\" height=\"8012\" alt=\"\" class=\"wp-block-jetpack-slideshow_image wp-image-1413\" data-id=\"1413\" src=\"https:\/\/leaebeling.de\/wp-content\/uploads\/2024\/11\/Paralysis.png\" srcset=\"https:\/\/leaebeling.de\/wp-content\/uploads\/2024\/11\/Paralysis.png 14234w, https:\/\/leaebeling.de\/wp-content\/uploads\/2024\/11\/Paralysis-300x169.png 300w, https:\/\/leaebeling.de\/wp-content\/uploads\/2024\/11\/Paralysis-1024x576.png 1024w, https:\/\/leaebeling.de\/wp-content\/uploads\/2024\/11\/Paralysis-1280x720.png 1280w, https:\/\/leaebeling.de\/wp-content\/uploads\/2024\/11\/Paralysis-768x432.png 768w, https:\/\/leaebeling.de\/wp-content\/uploads\/2024\/11\/Paralysis-1536x865.png 1536w, https:\/\/leaebeling.de\/wp-content\/uploads\/2024\/11\/Paralysis-2048x1153.png 2048w, https:\/\/leaebeling.de\/wp-content\/uploads\/2024\/11\/Paralysis-500x281.png 500w, https:\/\/leaebeling.de\/wp-content\/uploads\/2024\/11\/Paralysis-800x450.png 800w, https:\/\/leaebeling.de\/wp-content\/uploads\/2024\/11\/Paralysis-1920x1081.png 1920w\" sizes=\"auto, (max-width: 14234px) 100vw, 14234px\" \/><\/figure><\/li><li class=\"wp-block-jetpack-slideshow_slide swiper-slide\"><figure><img loading=\"lazy\" decoding=\"async\" width=\"14234\" height=\"8012\" alt=\"\" class=\"wp-block-jetpack-slideshow_image wp-image-1412\" data-id=\"1412\" src=\"https:\/\/leaebeling.de\/wp-content\/uploads\/2024\/11\/Numbness.png\" srcset=\"https:\/\/leaebeling.de\/wp-content\/uploads\/2024\/11\/Numbness.png 14234w, https:\/\/leaebeling.de\/wp-content\/uploads\/2024\/11\/Numbness-300x169.png 300w, https:\/\/leaebeling.de\/wp-content\/uploads\/2024\/11\/Numbness-1024x576.png 1024w, https:\/\/leaebeling.de\/wp-content\/uploads\/2024\/11\/Numbness-1280x720.png 1280w, https:\/\/leaebeling.de\/wp-content\/uploads\/2024\/11\/Numbness-768x432.png 768w, https:\/\/leaebeling.de\/wp-content\/uploads\/2024\/11\/Numbness-1536x865.png 1536w, https:\/\/leaebeling.de\/wp-content\/uploads\/2024\/11\/Numbness-2048x1153.png 2048w, https:\/\/leaebeling.de\/wp-content\/uploads\/2024\/11\/Numbness-500x281.png 500w, https:\/\/leaebeling.de\/wp-content\/uploads\/2024\/11\/Numbness-800x450.png 800w, https:\/\/leaebeling.de\/wp-content\/uploads\/2024\/11\/Numbness-1920x1081.png 1920w\" sizes=\"auto, (max-width: 14234px) 100vw, 14234px\" \/><\/figure><\/li><li class=\"wp-block-jetpack-slideshow_slide swiper-slide\"><figure><img loading=\"lazy\" decoding=\"async\" width=\"14240\" height=\"8018\" alt=\"\" class=\"wp-block-jetpack-slideshow_image wp-image-1415\" data-id=\"1415\" src=\"https:\/\/leaebeling.de\/wp-content\/uploads\/2024\/11\/surrender.png\" srcset=\"https:\/\/leaebeling.de\/wp-content\/uploads\/2024\/11\/surrender.png 14240w, https:\/\/leaebeling.de\/wp-content\/uploads\/2024\/11\/surrender-300x169.png 300w, https:\/\/leaebeling.de\/wp-content\/uploads\/2024\/11\/surrender-1024x577.png 1024w, https:\/\/leaebeling.de\/wp-content\/uploads\/2024\/11\/surrender-1280x721.png 1280w, https:\/\/leaebeling.de\/wp-content\/uploads\/2024\/11\/surrender-768x432.png 768w, https:\/\/leaebeling.de\/wp-content\/uploads\/2024\/11\/surrender-1536x865.png 1536w, https:\/\/leaebeling.de\/wp-content\/uploads\/2024\/11\/surrender-2048x1153.png 2048w, https:\/\/leaebeling.de\/wp-content\/uploads\/2024\/11\/surrender-500x282.png 500w, https:\/\/leaebeling.de\/wp-content\/uploads\/2024\/11\/surrender-800x450.png 800w, https:\/\/leaebeling.de\/wp-content\/uploads\/2024\/11\/surrender-1920x1081.png 1920w\" sizes=\"auto, (max-width: 14240px) 100vw, 14240px\" \/><\/figure><\/li><li class=\"wp-block-jetpack-slideshow_slide swiper-slide\"><figure><img loading=\"lazy\" decoding=\"async\" width=\"14234\" height=\"8012\" alt=\"\" class=\"wp-block-jetpack-slideshow_image wp-image-1416\" data-id=\"1416\" src=\"https:\/\/leaebeling.de\/wp-content\/uploads\/2024\/11\/The-Ethical-Neoliberal-Subject.png\" srcset=\"https:\/\/leaebeling.de\/wp-content\/uploads\/2024\/11\/The-Ethical-Neoliberal-Subject.png 14234w, https:\/\/leaebeling.de\/wp-content\/uploads\/2024\/11\/The-Ethical-Neoliberal-Subject-300x169.png 300w, https:\/\/leaebeling.de\/wp-content\/uploads\/2024\/11\/The-Ethical-Neoliberal-Subject-1024x576.png 1024w, https:\/\/leaebeling.de\/wp-content\/uploads\/2024\/11\/The-Ethical-Neoliberal-Subject-1280x720.png 1280w, https:\/\/leaebeling.de\/wp-content\/uploads\/2024\/11\/The-Ethical-Neoliberal-Subject-768x432.png 768w, https:\/\/leaebeling.de\/wp-content\/uploads\/2024\/11\/The-Ethical-Neoliberal-Subject-1536x865.png 1536w, https:\/\/leaebeling.de\/wp-content\/uploads\/2024\/11\/The-Ethical-Neoliberal-Subject-2048x1153.png 2048w, https:\/\/leaebeling.de\/wp-content\/uploads\/2024\/11\/The-Ethical-Neoliberal-Subject-500x281.png 500w, https:\/\/leaebeling.de\/wp-content\/uploads\/2024\/11\/The-Ethical-Neoliberal-Subject-800x450.png 800w, https:\/\/leaebeling.de\/wp-content\/uploads\/2024\/11\/The-Ethical-Neoliberal-Subject-1920x1081.png 1920w\" sizes=\"auto, (max-width: 14234px) 100vw, 14234px\" \/><\/figure><\/li><li class=\"wp-block-jetpack-slideshow_slide swiper-slide\"><figure><img loading=\"lazy\" decoding=\"async\" width=\"14234\" height=\"8012\" alt=\"\" class=\"wp-block-jetpack-slideshow_image wp-image-1417\" data-id=\"1417\" src=\"https:\/\/leaebeling.de\/wp-content\/uploads\/2024\/11\/Weltschmerz-sucks.png\" srcset=\"https:\/\/leaebeling.de\/wp-content\/uploads\/2024\/11\/Weltschmerz-sucks.png 14234w, https:\/\/leaebeling.de\/wp-content\/uploads\/2024\/11\/Weltschmerz-sucks-300x169.png 300w, https:\/\/leaebeling.de\/wp-content\/uploads\/2024\/11\/Weltschmerz-sucks-1024x576.png 1024w, https:\/\/leaebeling.de\/wp-content\/uploads\/2024\/11\/Weltschmerz-sucks-1280x720.png 1280w, https:\/\/leaebeling.de\/wp-content\/uploads\/2024\/11\/Weltschmerz-sucks-768x432.png 768w, https:\/\/leaebeling.de\/wp-content\/uploads\/2024\/11\/Weltschmerz-sucks-1536x865.png 1536w, https:\/\/leaebeling.de\/wp-content\/uploads\/2024\/11\/Weltschmerz-sucks-2048x1153.png 2048w, https:\/\/leaebeling.de\/wp-content\/uploads\/2024\/11\/Weltschmerz-sucks-500x281.png 500w, https:\/\/leaebeling.de\/wp-content\/uploads\/2024\/11\/Weltschmerz-sucks-800x450.png 800w, https:\/\/leaebeling.de\/wp-content\/uploads\/2024\/11\/Weltschmerz-sucks-1920x1081.png 1920w\" sizes=\"auto, (max-width: 14234px) 100vw, 14234px\" \/><\/figure><\/li><li class=\"wp-block-jetpack-slideshow_slide swiper-slide\"><figure><img loading=\"lazy\" decoding=\"async\" width=\"14234\" height=\"8012\" alt=\"\" class=\"wp-block-jetpack-slideshow_image wp-image-1408\" data-id=\"1408\" src=\"https:\/\/leaebeling.de\/wp-content\/uploads\/2024\/11\/Decolonize-knowledge.png\" srcset=\"https:\/\/leaebeling.de\/wp-content\/uploads\/2024\/11\/Decolonize-knowledge.png 14234w, https:\/\/leaebeling.de\/wp-content\/uploads\/2024\/11\/Decolonize-knowledge-300x169.png 300w, https:\/\/leaebeling.de\/wp-content\/uploads\/2024\/11\/Decolonize-knowledge-1024x576.png 1024w, https:\/\/leaebeling.de\/wp-content\/uploads\/2024\/11\/Decolonize-knowledge-1280x720.png 1280w, https:\/\/leaebeling.de\/wp-content\/uploads\/2024\/11\/Decolonize-knowledge-768x432.png 768w, https:\/\/leaebeling.de\/wp-content\/uploads\/2024\/11\/Decolonize-knowledge-1536x865.png 1536w, https:\/\/leaebeling.de\/wp-content\/uploads\/2024\/11\/Decolonize-knowledge-2048x1153.png 2048w, https:\/\/leaebeling.de\/wp-content\/uploads\/2024\/11\/Decolonize-knowledge-500x281.png 500w, https:\/\/leaebeling.de\/wp-content\/uploads\/2024\/11\/Decolonize-knowledge-800x450.png 800w, https:\/\/leaebeling.de\/wp-content\/uploads\/2024\/11\/Decolonize-knowledge-1920x1081.png 1920w\" sizes=\"auto, (max-width: 14234px) 100vw, 14234px\" \/><\/figure><\/li><li class=\"wp-block-jetpack-slideshow_slide swiper-slide\"><figure><img loading=\"lazy\" decoding=\"async\" width=\"14234\" height=\"8012\" alt=\"\" class=\"wp-block-jetpack-slideshow_image wp-image-1406\" data-id=\"1406\" src=\"https:\/\/leaebeling.de\/wp-content\/uploads\/2024\/11\/Act-now.png\" srcset=\"https:\/\/leaebeling.de\/wp-content\/uploads\/2024\/11\/Act-now.png 14234w, https:\/\/leaebeling.de\/wp-content\/uploads\/2024\/11\/Act-now-300x169.png 300w, https:\/\/leaebeling.de\/wp-content\/uploads\/2024\/11\/Act-now-1024x576.png 1024w, https:\/\/leaebeling.de\/wp-content\/uploads\/2024\/11\/Act-now-1280x720.png 1280w, https:\/\/leaebeling.de\/wp-content\/uploads\/2024\/11\/Act-now-768x432.png 768w, https:\/\/leaebeling.de\/wp-content\/uploads\/2024\/11\/Act-now-1536x865.png 1536w, https:\/\/leaebeling.de\/wp-content\/uploads\/2024\/11\/Act-now-2048x1153.png 2048w, https:\/\/leaebeling.de\/wp-content\/uploads\/2024\/11\/Act-now-500x281.png 500w, https:\/\/leaebeling.de\/wp-content\/uploads\/2024\/11\/Act-now-800x450.png 800w, https:\/\/leaebeling.de\/wp-content\/uploads\/2024\/11\/Act-now-1920x1081.png 1920w\" sizes=\"auto, (max-width: 14234px) 100vw, 14234px\" \/><\/figure><\/li><\/ul><a class=\"wp-block-jetpack-slideshow_button-prev swiper-button-prev swiper-button-white\" role=\"button\"><\/a><a class=\"wp-block-jetpack-slideshow_button-next swiper-button-next swiper-button-white\" role=\"button\"><\/a><a aria-label=\"Pause Slideshow\" class=\"wp-block-jetpack-slideshow_button-pause\" role=\"button\"><\/a><div class=\"wp-block-jetpack-slideshow_pagination swiper-pagination swiper-pagination-white\"><\/div><\/div><\/div>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-3a88641f wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<div style=\"height:71px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h6 class=\"wp-block-heading has-text-align-right has-contrast-2-color has-text-color has-link-color wp-elements-c9baa761a39655843de071bb2b8f0681\">Illustrations for a video<br>Hand drawn, ink on paper, digitally colorized<\/h6>\n\n\n\n<h6 class=\"wp-block-heading has-text-align-right has-contrast-2-color has-text-color has-link-color wp-elements-e0383c9370e447dd0a6f6049475c61f1\">The Affect and Colonialism Web Lab<\/h6>\n\n\n\n<h6 class=\"wp-block-heading has-text-align-right has-contrast-2-color has-text-color has-link-color wp-elements-6983478e24b6df69e6d49930f515e7e2\"><a href=\"https:\/\/affect-and-colonialism.net\/video\/weltschmerz-political-emotions-in-the-neoliberal-age\/\">https:\/\/affect-and-colonialism.net\/video\/weltschmerz-political-emotions-in-the-neoliberal-age\/<\/a><\/h6>\n\n\n\n<h6 class=\"wp-block-heading has-text-align-right has-contrast-2-color has-text-color has-link-color wp-elements-4183905dec872e6aff34a4167fd12437\">Berlin 2024<\/h6>\n<\/div>\n<\/div>\n<\/div>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>","protected":false},"excerpt":{"rendered":"<p>Political Emotions in the Neoliberal Age Illustrationen zur Veranschaulichung f\u00fcr ein Video \u00fcber Weltschmerz. Basierend auf einer selbstdurchgef\u00fchrten ethnografischen Studie. Illustrationen f\u00fcr VideoHandgezeichnet Tinte auf Papier, digital koloriert The Affect and Colonialism Web Lab https:\/\/affect-and-colonialism.net\/video\/weltschmerz-political-emotions-in-the-neoliberal-age\/ Berlin 2024<\/p>","protected":false},"author":1,"featured_media":2116,"comment_status":"open","ping_status":"open","sticky":false,"template":"wp-custom-template-single-item-post-full-width","format":"standard","meta":{"_vp_format_video_url":"","_vp_image_focal_point":[],"footnotes":""},"categories":[6,8],"tags":[],"class_list":["post-1405","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-illustration","category-wissenschaftskommunikation"],"_links":{"self":[{"href":"https:\/\/leaebeling.de\/en\/wp-json\/wp\/v2\/posts\/1405","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/leaebeling.de\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/leaebeling.de\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/leaebeling.de\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/leaebeling.de\/en\/wp-json\/wp\/v2\/comments?post=1405"}],"version-history":[{"count":4,"href":"https:\/\/leaebeling.de\/en\/wp-json\/wp\/v2\/posts\/1405\/revisions"}],"predecessor-version":[{"id":1794,"href":"https:\/\/leaebeling.de\/en\/wp-json\/wp\/v2\/posts\/1405\/revisions\/1794"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/leaebeling.de\/en\/wp-json\/wp\/v2\/media\/2116"}],"wp:attachment":[{"href":"https:\/\/leaebeling.de\/en\/wp-json\/wp\/v2\/media?parent=1405"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/leaebeling.de\/en\/wp-json\/wp\/v2\/categories?post=1405"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/leaebeling.de\/en\/wp-json\/wp\/v2\/tags?post=1405"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}